{"id":4069,"date":"2021-11-09T15:29:13","date_gmt":"2021-11-09T13:29:13","guid":{"rendered":"https:\/\/www.wddscyprus.com\/?post_type=tribe_events&#038;p=4069"},"modified":"2021-11-09T15:29:13","modified_gmt":"2021-11-09T13:29:13","slug":"internationales-kurzfilmfestival-oberhausen-internationalen-wettbewerb","status":"publish","type":"tribe_events","link":"https:\/\/www.wddscyprus.com\/de\/event\/internationales-kurzfilmfestival-oberhausen-internationalen-wettbewerb\/","title":{"rendered":"Internationales Kurzfilmfestival Oberhausen &#8222;Internationalen Wettbewerb&#8220;"},"content":{"rendered":"<p>Nach dem gro\u00dfen Erfolg der letztj\u00e4hrigen Tournee der Internationalen Kurzfilmtage Oberhausen auf Zypern freut sich das ARTos House in Zusammenarbeit mit dem Goethe-Institut die Programme &#8222;Preistr\u00e4ger 2020&#8220;\u00a0 am 19. November, den &#8222;Internationalen Wettbewerb&#8220; am 20. November und am 21. November &#8222;Made in Germany 3&#8220; jeweils um 20:00 Uhr in der ARTos House zu pr\u00e4sentieren.<\/p>\n<p>Im Laufe von sechs Jahrzehnten haben sich die Internationalen Kurzfilmtage Oberhausen zu einem der renommiertesten Kulturereignisse der Welt entwickelt &#8211; ein Ort, an dem ber\u00fchmte Pers\u00f6nlichkeiten wie Agn\u00e8s Varda, Martin Scorsese, Alexander Kluge und Werner Herzog erstmals ihre Filme zeigten. Oberhausen ist das \u00e4lteste Kurzfilmfestival der Welt und genie\u00dft mittlerweile auch in der Kunstszene einen hervorragenden Ruf, in der Kurzfilme und Videos heute eine immer wichtigere Rolle spielen.<\/p>\n<h4>Vorf\u00fchrung am 20. November<\/h4>\n<p>Dieses Programm zeigt einige der interessantesten Filme des Internationalen Wettbewerbs 2020. 1982 wurden die indigene Gemeinschaft der Zoque durch den Ausbruch eines Vulkans gezwungen, umzusiedeln. \u201e( ( ( ( ( \/*\\ ) ) ) ) ) )\u201c ist das Portrait eines Dorfes in Chiapas, Mexiko, seiner Kultur, seiner Ger\u00e4usche und seiner Architektur. Der Film dokumentiert die modernen Herausforderungen und die Weltsicht einer Gemeinschaft, die auch unter politischem Druck steht, ihr Land und ihre Rechte zu bewahren. Auch im Spielfilm \u201eO Jardim Fant\u00e1stico\u201c spielt indigene Kultur eine wichtige Rolle. Hier verabreicht eine Lehrerin in ihrem Unterricht, einer alten Tradition folgend, Ayahuasca, um ihren Sch\u00fclern andere Realit\u00e4tsebenen zu vermitteln. In \u201eBELLA\u201c von Thelyia Petraki verschwimmen die Grenzen zwischen Spiel- und Dokumentarfilm, wenn sich im Griechenland der sp\u00e4ten 1980er Jahre vor den Augen der idealistischen Arbeiterin Anthi erst das Land, dann die Welt und vielleicht sogar ihr pers\u00f6nliches Umfeld gravierend ver\u00e4ndern. In \u201eGira Ancora\u201c durchstreift ein Heranwachsender sein Viertel in Palermo. In der Tradition des Neorealismus l\u00e4sst uns die Kamera am Leben dieser Gemeinschaft teilhaben und zeigt gleichzeitig, wie die Ger\u00fcchte \u00fcber seine Mutter ihn allm\u00e4hlich zum Au\u00dfenseiter machen. Die Welt des Protagonisten zieht sich in immer engeren Kreisen zusammen.<\/p>\n<h4>Internationaler Wettbewerb<\/h4>\n<p>&nbsp;<\/p>\n<p>O Jardim Fant\u00e1stico\/ the fantastic garden<\/p>\n<p>Tico Dias\/F\u00e1bio Baldo, Brazil 2019,<\/p>\n<p>colour, Portuguese with English subs, 21\u2018<\/p>\n<p>&nbsp;<\/p>\n<p>( ( ( ( ( \/*\\ ) ) ) ) )<\/p>\n<p>Sa\u00fal Kak\/Charles Fairbanks, Mexico 2019,<\/p>\n<p>colour, Spanish with English subs, 18\u201830\u2018\u2018<\/p>\n<p>&nbsp;<\/p>\n<p>BELLA<\/p>\n<p>Thelyia Petraki, Greece 2020, colour,<\/p>\n<p>Greek, English, Russian with English subs, 24\u201830\u2018\u2018<\/p>\n<p>&nbsp;<\/p>\n<p>Gira Ancora\/ One more Round<\/p>\n<p>Elena Petitpierre, Switzerland 2019,<\/p>\n<p>colour, Italian with English subs, 22<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach dem gro\u00dfen Erfolg der letztj\u00e4hrigen Tournee der Internationalen Kurzfilmtage Oberhausen auf Zypern freut sich das ARTos House in Zusammenarbeit mit dem Goethe-Institut die Programme &#8222;Preistr\u00e4ger 2020&#8220;\u00a0 am 19. November, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4108,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[35,167],"tribe_events_cat":[132,131],"class_list":["post-4069","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-film-de","tag-goethe-institut","tribe_events_cat-film-de-2","tribe_events_cat-veranstaltungen2021","cat_film-de-2","cat_veranstaltungen2021"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/4069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/4069\/revisions"}],"predecessor-version":[{"id":4126,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/4069\/revisions\/4126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media\/4108"}],"wp:attachment":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media?parent=4069"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tags?post=4069"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=4069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}