{"id":5795,"date":"2022-10-24T10:28:20","date_gmt":"2022-10-24T07:28:20","guid":{"rendered":"https:\/\/www.wddscyprus.com\/?post_type=tribe_events&#038;p=5795"},"modified":"2022-10-24T10:28:20","modified_gmt":"2022-10-24T07:28:20","slug":"oberhausen-on-tour-in-nikosia-art-and-experiment","status":"publish","type":"tribe_events","link":"https:\/\/www.wddscyprus.com\/de\/event\/oberhausen-on-tour-in-nikosia-art-and-experiment\/","title":{"rendered":"Oberhausen on Tour in Nikosia &#8211; Art and Experiment"},"content":{"rendered":"<p>Das Goethe-Institut Zypern und ARTos House freuen sich, im November drei Kurzfilmprogramme der 67. Internationalen Kurzfilmtage Oberhausen zu pr\u00e4sentieren. Die Vorf\u00fchrungen im ARTos House beginnen am Mittwoch, den 2. November, mit f\u00fcnf Filmen aus dem Deutschen Wettbewerbsprogramm 2021. Am Donnerstag, 3. November, werden die f\u00fcnf Filme des\u00a0 Programms<em> Art and Experiment<\/em> pr\u00e4sentiert. Der\u00a0 dritte und letzte Abend am Freitag, 4. November ist\u00a0 den elf Filmen des Musikvideo-Preis-Programms gewidmet.<\/p>\n<p><strong>Art and Experiment<\/strong><\/p>\n<p>Diese sechs Arbeiten zwischen Black Box und White Cube bedienen sich zum Teil sehr ungew\u00f6hnlicher \u00c4sthetiken und Techniken. \u201ePole \u017din\u201c befasst sich mit der Entwicklung der nordb\u00f6hmischen Landschaft und ihrem aktuellen Zustand. Fremde Videobeitr\u00e4ge zeigen die Bem\u00fchungen, L\u00f6sungen zu finden und spezifische utopische Ideen umzusetzen. \u201e{if your bait can sing the wild one will come} Like Shadows Through Leaves\u201c ist eine k\u00fcnstlerische und investigative Erkundung, die die Beziehungen zwischen Kultur und Klimawandel neu denkt. \u201eSz\u00e9phercegn\u0151\u201c beschreibt den Konflikt zwischen den eigenen Bewegungen und den zwangsl\u00e4ufigen Einschr\u00e4nkungen derselben als kombinierte Animation mit physikalisch-basierten Simulationen.<\/p>\n<p>\u201eUn tr\u00e8s long temps d\u00b4exposition\u201c entdeckt, schichtet und verbindet Bilder und Narrative der Welt- und Privatgeschichte. Mit ihrer zugleich analytischen Komposition von Bildmotivketten macht Chlo\u00e9 Galibert-La\u00een\u00e9 die politisch-ideologische Dimension bildgebender technologischer Verfahren sichtbar. \u201eDoors of Reception\u201c ist eine Collage aus T\u00fcrger\u00e4uschen verschiedener Science-Fiction-Filme, die ein abstraktes Klanggem\u00e4lde aus sich \u00f6ffnenden und schlie\u00dfenden Farbfeldern ergeben. \u201eBefore the fall there was no fall. Episode 02: surfaces\u201c schlie\u00dflich zeigt anhand der Stadt Srebrenica wie sich historische Spuren manifestieren an Orten, die grausame Zeitgeschichte schrieben, und wie die allm\u00e4hlich verblassenden Graffiti des Terrors ein Wandgem\u00e4lde der Zeugenschaft des Genozids evozieren.<\/p>\n<p><strong>Pole \u017din (Fields of \u017dinas)<\/strong><br \/>\nMarie Luk\u00e1\u010dov\u00e1\/Anna Reme\u0161ov\u00e1, Tschechien 2020,<br \/>\nFarbe, Tschechisch mit englischen Untertiteln, 9\u2019<\/p>\n<p><strong>{if your bait can sing the wild one will come}<\/strong> <strong>Like Shadows Through Leaves<\/strong><br \/>\nLucy Davis, Singapur\/Finnland 2020<br \/>\nFarbe, Englisch\/Malaiisch\/Hokkien\/Mandarin\/Tamil mit englischen Untertiteln, 28\u2019<\/p>\n<p><strong>Sz\u00e9phercegn\u0151 (Princess Beauty)<\/strong><br \/>\nEszter Szab\u00f3, Ungarn 2020<br \/>\nFarbe, Englisch, 2\u201930\u2019\u2019<\/p>\n<p><strong>Un tr\u00e8s long temps d\u2019exposition (A Very Long Exposure Time)<\/strong><br \/>\nChlo\u00e9 Galibert-La\u00een\u00e9, Frankreich 2020<br \/>\nFarbe, kein Text, Englisch, 7\u2019<\/p>\n<p><strong>Doors of Reception<\/strong><br \/>\nBj\u00f8rn Melhus, Deutschland 2021<br \/>\nFarbe, Kein Text, 2\u201930\u2019\u2019<\/p>\n<p><strong>Before the fall there was no fall. Episode 02: surfaces<\/strong><br \/>\nAnna Dasovi\u0107, Bosnien und Herzegowina\/Niederlande 2020<br \/>\nFarbe, Bosnisch\/Niederl\u00e4ndisch mit englischen Untertiteln, 20\u2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Goethe-Institut Zypern und ARTos House freuen sich, im November drei Kurzfilmprogramme der 67. Internationalen Kurzfilmtage Oberhausen zu pr\u00e4sentieren. Die Vorf\u00fchrungen im ARTos House beginnen am Mittwoch, den 2. November, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5790,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[207],"class_list":["post-5795","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-film-veranstaltungen-2022","cat_film-veranstaltungen-2022"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/5795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/5795\/revisions"}],"predecessor-version":[{"id":5796,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/5795\/revisions\/5796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media\/5790"}],"wp:attachment":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media?parent=5795"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tags?post=5795"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=5795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}