{"id":7844,"date":"2025-10-31T01:21:14","date_gmt":"2025-10-30T23:21:14","guid":{"rendered":"https:\/\/www.wddscyprus.com\/?post_type=tribe_events&#038;p=7844"},"modified":"2025-10-31T12:44:58","modified_gmt":"2025-10-31T10:44:58","slug":"the-art-of-making","status":"publish","type":"tribe_events","link":"https:\/\/www.wddscyprus.com\/de\/event\/the-art-of-making\/","title":{"rendered":"The Art of Making"},"content":{"rendered":"<p>Drei Jahre nach der vom Goethe-Institut Zypernunterst\u00fctzen, dokumentarischen Ausstellung <strong>The Art of Making<\/strong>, die das Leben, die Motivationen und die Herausforderungen von 20 Handwerkerinnen und Handwerkern in Deutschland und Zypern beleuchtete, wird ein Vortrag diese Themen aufgreifen und untersuchen, wie sich die Handwerkslandschaft seither entwickelt hat. Im Vortrag wird es um pers\u00f6nliche Geschichten von Handwerker*innen aus der Ausstellung gehen, das aktuelle Handwerksbildungssystem in Deutschland wird erl\u00e4utert, und die Frage gestellt, ob Handwerk heute der Gesellschaft dient oder zu einer romantisierten Tradition geworden ist. Eine anschlie\u00dfende Podiumsdiskussion wird den Fokus auf Zypern richten und die Herausforderungen, Chancen und den sozialen Status der Handwerker im zeitgen\u00f6ssischen zypriotischen Kontext thematisieren.<\/p>\n<p>&nbsp;<\/p>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Teilnehmer der Podiumsdiskussion:\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><strong><span class=\"Y2IQFc\" lang=\"de\">Teilnehmer der Podiumsdiskussion:<\/span><\/strong><\/p>\n<p>\u2013 <span class=\"Y2IQFc\" lang=\"de\">Koordinierung<\/span>: Achilleas Kentonis, Managing Director ARTos House<\/p>\n<p>\u2013 Mrs Andrea Charalambides<\/p>\n<p>\u2013 Mr Konstantinos Kashiotis<\/p>\n<p>\u2013 Mr Georgios N. Paparoditis<\/p>\n<p>&nbsp;<\/p>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Zeitplan: 17:00\u201317:15 Begr\u00fc\u00dfung 17:15\u201318:00 Vortrag 18:00\u201318:30 Podiumsdiskussion 18:30 Abschluss\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><strong><span class=\"Y2IQFc\" lang=\"de\">Zeitplan: <\/span><\/strong><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Zeitplan: 17:00\u201317:15 Begr\u00fc\u00dfung 17:15\u201318:00 Vortrag 18:00\u201318:30 Podiumsdiskussion 18:30 Abschluss\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><span class=\"Y2IQFc\" lang=\"de\">17:00\u201317:15 Begr\u00fc\u00dfung <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Zeitplan: 17:00\u201317:15 Begr\u00fc\u00dfung 17:15\u201318:00 Vortrag 18:00\u201318:30 Podiumsdiskussion 18:30 Abschluss\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><span class=\"Y2IQFc\" lang=\"de\">17:15\u201318:00 Vortrag <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Zeitplan: 17:00\u201317:15 Begr\u00fc\u00dfung 17:15\u201318:00 Vortrag 18:00\u201318:30 Podiumsdiskussion 18:30 Abschluss\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><span class=\"Y2IQFc\" lang=\"de\">18:00\u201318:30 Podiumsdiskussion <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Translation\" aria-label=\"Translated text: Zeitplan: 17:00\u201317:15 Begr\u00fc\u00dfung 17:15\u201318:00 Vortrag 18:00\u201318:30 Podiumsdiskussion 18:30 Abschluss\" data-ved=\"2ahUKEwi70vHThs2QAxVMTKQEHadoAuIQ3ewLegQICxAW\"><span class=\"Y2IQFc\" lang=\"de\">18:30 Abschluss<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drei Jahre nach der vom Goethe-Institut Zypernunterst\u00fctzen, dokumentarischen Ausstellung The Art of Making, die das Leben, die Motivationen und die Herausforderungen von 20 Handwerkerinnen und Handwerkern in Deutschland und Zypern [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":8003,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[437,417,211],"tribe_events_cat":[523,515,524],"class_list":["post-7844","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-ausstellung","tag-nikosia","tag-vortrag","tribe_events_cat-ausstellung-veranstaltungen-2025","tribe_events_cat-veranstaltungen-2025","tribe_events_cat-vortrag-veranstaltungen-2025","cat_ausstellung-veranstaltungen-2025","cat_veranstaltungen-2025","cat_vortrag-veranstaltungen-2025"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/7844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":2,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/7844\/revisions"}],"predecessor-version":[{"id":8006,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events\/7844\/revisions\/8006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media\/8003"}],"wp:attachment":[{"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/media?parent=7844"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tags?post=7844"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.wddscyprus.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=7844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}